{"id":36413,"date":"2019-08-16T01:33:26","date_gmt":"2019-08-16T04:33:26","guid":{"rendered":"https:\/\/www.samnaz.org\/?p=28631"},"modified":"2021-11-26T11:09:16","modified_gmt":"2021-11-26T14:09:16","slug":"campamento-de-jovenes-prepara2-2019","status":"publish","type":"post","link":"https:\/\/www.samnaz.org\/pt\/campamento-de-jovenes-prepara2-2019\/","title":{"rendered":"CAMPAMENTO DE J\u00d3VENES \u201cPREPARA2 2019\u201d"},"content":{"rendered":"<p>[et_pb_section bb_built=\u00bb1&#8243; _builder_version=\u00bb3.0.47&#8243; custom_padding=\u00bb0px|0px|3px|0px\u00bb][et_pb_row _builder_version=\u00bb3.0.47&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_padding=\u00bb43px|0px|0px|0px\u00bb][et_pb_column type=\u00bb2_3&#8243;][et_pb_post_title categories=\u00bboff\u00bb _builder_version=\u00bb3.0.105&#8243; title_font=\u00bb||||||||\u00bb title_font_size=\u00bb35px\u00bb title_text_color=\u00bb#db6553&#8243; meta_font=\u00bb||||||||\u00bb meta_font_size=\u00bb13px\u00bb \/][et_pb_text _builder_version=\u00bb3.0.105&#8243; background_layout=\u00bblight\u00bb]<\/p>\n<p style=\"text-align: justify;\"><strong>(CNAS Per\u00fa<\/strong><strong>)<\/strong> El gran colegio Fidencio Hidalgo Flores del distrito de Nueva Cajamarca en la regi\u00f3n San Mart\u00edn, fue escenario del campamento juvenil nazareno que organiz\u00f3 la JNI del distrito Per\u00fa Utcubamba, con el lema <em>PREPARA2 2019<\/em>, del 3 al 6 de agosto del presente.<\/p>\n<p style=\"text-align: justify;\">M\u00e1s de 300 j\u00f3venes llenos de vigor y entusiasmo se inscribieron y participaron en temas y talleres sobre la santidad, y por las noches cultos evangel\u00edsticos con m\u00fasica, testimonios y la predicaci\u00f3n de la bendita Palabra de Dios.<\/p>\n<p style=\"text-align: justify;\">El Rev. Ad\u00e1n S\u00e1nchez comparti\u00f3 en el d\u00eda temas relacionados a los j\u00f3venes y su comuni\u00f3n con Dios. El predicador Hermigrando Rivera comparti\u00f3 en los talleres y predicaciones evangel\u00edsticas por las noches. \u00a0Dios us\u00f3 su testimonio de vida, sus exposiciones b\u00edblicas, por lo que, ante el llamado, la juventud se rindi\u00f3 a los pies de Jesucristo renovando votos de fidelidad y una gran cantidad de j\u00f3venes se han reconciliado con su Se\u00f1or.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n en la zona del Alto Mayo, la juventud ha tenido momentos deportivos y caminatas a los principales lugares tur\u00edsticos, especialmente al Tioyacu, de donde nacen las aguas cristalinas, que con el devenir de los a\u00f1os ha sido acondicionado por los lugare\u00f1os, para dar la bienvenida a los visitantes nacionales y extranjeros.<\/p>\n<p style=\"text-align: justify;\">Gracias a Dios por permitir que PREPARA2 se desarrolle de una manera asombrosa. Gracias a todo el equipo de JNI. Gracias a los distritos Per\u00fa Nororiente y Per\u00fa Norte por su presencia y apoyo. Gracias a todos los campistas por participar de este gran campamento que ha sido de mucha bendici\u00f3n, manifest\u00f3 el presidente Distrital.<\/p>\n<p style=\"text-align: justify;\" class=\"translation-block\"><strong> <em> Fonte: <\/em> <\/strong> <em> Communications Nazarenas Peru <\/em><\/p>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=\u00bb28632,28633,28634,28635,28636,28637&#8243; show_title_and_caption=\u00bboff\u00bb _builder_version=\u00bb3.0.105&#8243; pagination_font_size_tablet=\u00bb51&#8243; pagination_line_height_tablet=\u00bb2&#8243; show_pagination=\u00bbon\u00bb fullwidth=\u00bboff\u00bb orientation=\u00bblandscape\u00bb zoom_icon_color=\u00bb#db6553&#8243; hover_overlay_color=\u00bbrgba(255,255,255,0.9)\u00bb background_layout=\u00bblight\u00bb \/][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243;][et_pb_sidebar orientation=\u00bbright\u00bb area=\u00bbsidebar-1&#8243; show_border=\u00bboff\u00bb _builder_version=\u00bb3.0.105&#8243; header_font_size=\u00bb14&#8243; header_text_color=\u00bb#db6553&#8243; text_orientation=\u00bbright\u00bb \/][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>(CNAS Per\u00fa) El gran colegio Fidencio Hidalgo Flores del distrito de Nueva Cajamarca en la regi\u00f3n San Mart\u00edn, fue escenario del campamento juvenil nazareno que organiz\u00f3 la JNI del distrito Per\u00fa Utcubamba, con el lema PREPARA2 2019, del 3 al 6 de agosto del presente. M\u00e1s de 300 j\u00f3venes llenos de vigor y entusiasmo se [&hellip;]<\/p>","protected":false},"author":4,"featured_media":36419,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[50,56],"tags":[],"class_list":["post-36413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jni","category-peru"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.6 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CAMPAMENTO DE J\u00d3VENES \u201cPREPARA2 2019\u201d | Iglesia del Nazareno Am\u00e9rica del Sur<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAMPAMENTO DE J\u00d3VENES \u201cPREPARA2 2019\u201d | Iglesia del Nazareno Am\u00e9rica del Sur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.samnaz.org\/pt\/campamento-de-jovenes-prepara2-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Iglesia del Nazareno Am\u00e9rica del Sur\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazarenoEsp\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-16T04:33:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-26T14:09:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.samnaz.org\/wp-content\/uploads\/2019\/08\/1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"641\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Samnaz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Samnaz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/pt\\\/campamento-de-jovenes-prepara2-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/pt\\\/campamento-de-jovenes-prepara2-2019\\\/\"},\"author\":{\"name\":\"Samnaz\",\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#\\\/schema\\\/person\\\/c09d1131c49ba510c7e1cbb677b39927\"},\"headline\":\"CAMPAMENTO DE J\u00d3VENES \u201cPREPARA2 2019\u201d\",\"datePublished\":\"2019-08-16T04:33:26+00:00\",\"dateModified\":\"2021-11-26T14:09:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/pt\\\/campamento-de-jovenes-prepara2-2019\\\/\"},\"wordCount\":437,\"publisher\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/pt\\\/campamento-de-jovenes-prepara2-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samnaz.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1-2.jpg\",\"articleSection\":[\"JNI\",\"Per\u00fa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/pt\\\/campamento-de-jovenes-prepara2-2019\\\/\",\"url\":\"https:\\\/\\\/www.samnaz.org\\\/pt\\\/campamento-de-jovenes-prepara2-2019\\\/\",\"name\":\"CAMPAMENTO DE J\u00d3VENES \u201cPREPARA2 2019\u201d | Iglesia del Nazareno Am\u00e9rica del Sur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/pt\\\/campamento-de-jovenes-prepara2-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/pt\\\/campamento-de-jovenes-prepara2-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samnaz.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1-2.jpg\",\"datePublished\":\"2019-08-16T04:33:26+00:00\",\"dateModified\":\"2021-11-26T14:09:16+00:00\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.samnaz.org\\\/pt\\\/campamento-de-jovenes-prepara2-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/pt\\\/campamento-de-jovenes-prepara2-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.samnaz.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.samnaz.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1-2.jpg\",\"width\":1280,\"height\":641},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#website\",\"url\":\"https:\\\/\\\/www.samnaz.org\\\/\",\"name\":\"Haciendo Disc\u00edpulos Semejantes a Cristo en las naciones\",\"description\":\"Haciendo disc\u00edpulos semejantes a Cristo en las Naciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#organization\"},\"alternateName\":\"Viviendo la Gran Comisi\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.samnaz.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#organization\",\"name\":\"Iglesia del Nazareno Am\u00e9rica del Sur\",\"url\":\"https:\\\/\\\/www.samnaz.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.samnaz.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Logo-3-ESP.png\",\"contentUrl\":\"https:\\\/\\\/www.samnaz.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Logo-3-ESP.png\",\"width\":1041,\"height\":780,\"caption\":\"Iglesia del Nazareno Am\u00e9rica del Sur\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazarenoEsp\",\"https:\\\/\\\/www.instagram.com\\\/nazarenoesp\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/www.samnaz.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#\\\/schema\\\/person\\\/c09d1131c49ba510c7e1cbb677b39927\",\"name\":\"Samnaz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5baaf0e270319d09c0efce6a9dd03ff93175913c70afe26595c0069c83fa6dc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5baaf0e270319d09c0efce6a9dd03ff93175913c70afe26595c0069c83fa6dc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5baaf0e270319d09c0efce6a9dd03ff93175913c70afe26595c0069c83fa6dc?s=96&d=mm&r=g\",\"caption\":\"Samnaz\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CAMPAMENTO DE J\u00d3VENES \u201cPREPARA2 2019\u201d | Iglesia del Nazareno Am\u00e9rica del Sur","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"CAMPAMENTO DE J\u00d3VENES \u201cPREPARA2 2019\u201d | Iglesia del Nazareno Am\u00e9rica del Sur","og_url":"https:\/\/www.samnaz.org\/pt\/campamento-de-jovenes-prepara2-2019\/","og_site_name":"Iglesia del Nazareno Am\u00e9rica del Sur","article_publisher":"https:\/\/www.facebook.com\/NazarenoEsp","article_published_time":"2019-08-16T04:33:26+00:00","article_modified_time":"2021-11-26T14:09:16+00:00","og_image":[{"width":1280,"height":641,"url":"https:\/\/www.samnaz.org\/wp-content\/uploads\/2019\/08\/1-2.jpg","type":"image\/jpeg"}],"author":"Samnaz","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Samnaz","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.samnaz.org\/pt\/campamento-de-jovenes-prepara2-2019\/#article","isPartOf":{"@id":"https:\/\/www.samnaz.org\/pt\/campamento-de-jovenes-prepara2-2019\/"},"author":{"name":"Samnaz","@id":"https:\/\/www.samnaz.org\/#\/schema\/person\/c09d1131c49ba510c7e1cbb677b39927"},"headline":"CAMPAMENTO DE J\u00d3VENES \u201cPREPARA2 2019\u201d","datePublished":"2019-08-16T04:33:26+00:00","dateModified":"2021-11-26T14:09:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.samnaz.org\/pt\/campamento-de-jovenes-prepara2-2019\/"},"wordCount":437,"publisher":{"@id":"https:\/\/www.samnaz.org\/#organization"},"image":{"@id":"https:\/\/www.samnaz.org\/pt\/campamento-de-jovenes-prepara2-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.samnaz.org\/wp-content\/uploads\/2019\/08\/1-2.jpg","articleSection":["JNI","Per\u00fa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.samnaz.org\/pt\/campamento-de-jovenes-prepara2-2019\/","url":"https:\/\/www.samnaz.org\/pt\/campamento-de-jovenes-prepara2-2019\/","name":"CAMPAMENTO DE J\u00d3VENES \u201cPREPARA2 2019\u201d | Iglesia del Nazareno Am\u00e9rica del Sur","isPartOf":{"@id":"https:\/\/www.samnaz.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.samnaz.org\/pt\/campamento-de-jovenes-prepara2-2019\/#primaryimage"},"image":{"@id":"https:\/\/www.samnaz.org\/pt\/campamento-de-jovenes-prepara2-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.samnaz.org\/wp-content\/uploads\/2019\/08\/1-2.jpg","datePublished":"2019-08-16T04:33:26+00:00","dateModified":"2021-11-26T14:09:16+00:00","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.samnaz.org\/pt\/campamento-de-jovenes-prepara2-2019\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.samnaz.org\/pt\/campamento-de-jovenes-prepara2-2019\/#primaryimage","url":"https:\/\/www.samnaz.org\/wp-content\/uploads\/2019\/08\/1-2.jpg","contentUrl":"https:\/\/www.samnaz.org\/wp-content\/uploads\/2019\/08\/1-2.jpg","width":1280,"height":641},{"@type":"WebSite","@id":"https:\/\/www.samnaz.org\/#website","url":"https:\/\/www.samnaz.org\/","name":"Haciendo Disc\u00edpulos Semejantes a Cristo en las naciones","description":"Haciendo disc\u00edpulos semejantes a Cristo en las Naciones","publisher":{"@id":"https:\/\/www.samnaz.org\/#organization"},"alternateName":"Viviendo la Gran Comisi\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.samnaz.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.samnaz.org\/#organization","name":"Iglesia del Nazareno Am\u00e9rica del Sur","url":"https:\/\/www.samnaz.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.samnaz.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.samnaz.org\/wp-content\/uploads\/2021\/04\/Logo-3-ESP.png","contentUrl":"https:\/\/www.samnaz.org\/wp-content\/uploads\/2021\/04\/Logo-3-ESP.png","width":1041,"height":780,"caption":"Iglesia del Nazareno Am\u00e9rica del Sur"},"image":{"@id":"https:\/\/www.samnaz.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazarenoEsp","https:\/\/www.instagram.com\/nazarenoesp\/"],"publishingPrinciples":"https:\/\/www.samnaz.org\/"},{"@type":"Person","@id":"https:\/\/www.samnaz.org\/#\/schema\/person\/c09d1131c49ba510c7e1cbb677b39927","name":"Samnaz","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a5baaf0e270319d09c0efce6a9dd03ff93175913c70afe26595c0069c83fa6dc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a5baaf0e270319d09c0efce6a9dd03ff93175913c70afe26595c0069c83fa6dc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a5baaf0e270319d09c0efce6a9dd03ff93175913c70afe26595c0069c83fa6dc?s=96&d=mm&r=g","caption":"Samnaz"}}]}},"_links":{"self":[{"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/posts\/36413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/comments?post=36413"}],"version-history":[{"count":1,"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/posts\/36413\/revisions"}],"predecessor-version":[{"id":36447,"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/posts\/36413\/revisions\/36447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/media\/36419"}],"wp:attachment":[{"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/media?parent=36413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/categories?post=36413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/tags?post=36413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}