{"id":37033,"date":"2021-08-26T22:45:49","date_gmt":"2021-08-27T01:45:49","guid":{"rendered":"https:\/\/www.samnaz.org\/?p=35150"},"modified":"2021-11-26T11:09:04","modified_gmt":"2021-11-26T14:09:04","slug":"ministerio-cafe-en-colombia-empieza-a-consolidarse","status":"publish","type":"post","link":"https:\/\/www.samnaz.org\/pt\/ministerio-cafe-en-colombia-empieza-a-consolidarse\/","title":{"rendered":"MINIST\u00c9RIO DO CAF\u00c9 NA COL\u00d4MBIA COME\u00c7A A CONSOLIDAR"},"content":{"rendered":"[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb3.22&#8243; custom_padding=\u00bb0px|0px|3px|0px\u00bb][et_pb_row _builder_version=\u00bb3.25&#8243; column_structure=\u00bb2_3,1_3&#8243;][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_post_title categories=\u00bboff\u00bb _builder_version=\u00bb3.0.105&#8243; title_font=\u00bb||||||||\u00bb title_text_color=\u00bb#db6553&#8243; title_font_size=\u00bb35px\u00bb meta_font=\u00bb||||||||\u00bb meta_font_size=\u00bb13px\u00bb][\/et_pb_post_title][et_pb_text _builder_version=\u00bb4.9.2&#8243; hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p style=\"text-align: justify;\" class=\"translation-block\"><strong> (CNAS Col\u00f4mbia) <\/strong> O minist\u00e9rio do casamento <em> \u201cCasados \u200b\u200bFelices\u201d (CAF\u00c9), <\/em> da miss\u00e3o do Nazareno na Col\u00f4mbia, come\u00e7ou a consolidar a sua equipa nacional com o primeiro encontro de casais dos minist\u00e9rios CAFE das igrejas do Nazareno do pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">Esta nomea\u00e7\u00e3o ocorre 1 m\u00eas ap\u00f3s o congresso com o Dr. Sixto Porras onde a Venezuela e a Col\u00f4mbia participaram. Esse congresso foi o ponto de partida para os Pastores Frank e Maria Isabel Zuluaga como coordenadores do minist\u00e9rio CAFE na Col\u00f4mbia para come\u00e7ar a ministrar uma vez por m\u00eas via Zoom para os diferentes casais de minist\u00e9rio na Col\u00f4mbia.<\/p>\n<p style=\"text-align: justify;\" class=\"translation-block\">Nesta ocasi\u00e3o participaram mais de 140 pessoas, o que representa 85% do actual registo de casais que o minist\u00e9rio possui a n\u00edvel nacional. Hoje o minist\u00e9rio tem sua p\u00e1gina no Facebook <em> \u201cCasados \u200b\u200bFelices Col\u00f4mbia\u201d <\/em> e uma linha no WhatsApp para ser informado sobre as pr\u00f3ximas reuni\u00f5es, semin\u00e1rios, eventos e congressos do minist\u00e9rio em n\u00edvel local, distrital e nacional.<\/p>\n<p style=\"text-align: justify;\" class=\"translation-block\"><strong> <em> Fonte: <\/em> <\/strong> <em> Comunica\u00e7\u00f5es Igreja do Altar de Deus do Nazareno <\/em><\/p>\n<p style=\"text-align: justify;\">[\/et_pb_text][et_pb_gallery gallery_ids=\u00bb35028&#8243; show_title_and_caption=\u00bboff\u00bb _builder_version=\u00bb4.9.2&#8243; hover_enabled=\u00bb0&#8243; pagination_font_size_tablet=\u00bb51&#8243; pagination_line_height_tablet=\u00bb2&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_gallery][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_sidebar orientation=\u00bbright\u00bb area=\u00bbsidebar-1&#8243; _builder_version=\u00bb3.0.105&#8243; header_text_color=\u00bb#db6553&#8243; header_font_size=\u00bb14&#8243; text_orientation=\u00bbright\u00bb][\/et_pb_sidebar][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>(CNAS Colombia) El ministerio de matrimonios \u201cCasados Felices\u201d (CAF\u00c9), de la misi\u00f3n del Nazareno en Colombia, empez\u00f3 a consolidar su equipo nacional con el primer encuentro de parejas de los ministerios CAFE de las iglesias nazarenas del pa\u00eds. Esta cita se da 1 mes despu\u00e9s del congreso con el Dr. Sixto Porras donde particip\u00f3 Venezuela [&hellip;]<\/p>","protected":false},"author":4,"featured_media":37034,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"2880","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[8,64],"tags":[],"class_list":["post-37033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colombia","category-matrimonios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.6 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>MINISTERIO CAFE EN COLOMBIA EMPIEZA A CONSOLIDARSE | Iglesia del Nazareno Am\u00e9rica del Sur<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MINISTERIO CAFE EN COLOMBIA EMPIEZA A CONSOLIDARSE | Iglesia del Nazareno Am\u00e9rica del Sur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.samnaz.org\/pt\/ministerio-cafe-en-colombia-empieza-a-consolidarse\/\" \/>\n<meta property=\"og:site_name\" content=\"Iglesia del Nazareno Am\u00e9rica del Sur\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazarenoEsp\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-27T01:45:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-26T14:09:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.samnaz.org\/wp-content\/uploads\/2021\/08\/Pantallazos-CAFE-Colombia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Samnaz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Samnaz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/ministerio-cafe-en-colombia-empieza-a-consolidarse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/ministerio-cafe-en-colombia-empieza-a-consolidarse\\\/\"},\"author\":{\"name\":\"Samnaz\",\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#\\\/schema\\\/person\\\/c09d1131c49ba510c7e1cbb677b39927\"},\"headline\":\"MINISTERIO CAFE EN COLOMBIA EMPIEZA A CONSOLIDARSE\",\"datePublished\":\"2021-08-27T01:45:49+00:00\",\"dateModified\":\"2021-11-26T14:09:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/ministerio-cafe-en-colombia-empieza-a-consolidarse\\\/\"},\"wordCount\":319,\"publisher\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/ministerio-cafe-en-colombia-empieza-a-consolidarse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samnaz.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Pantallazos-CAFE-Colombia.png\",\"articleSection\":[\"Colombia\",\"Matrimonios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/ministerio-cafe-en-colombia-empieza-a-consolidarse\\\/\",\"url\":\"https:\\\/\\\/www.samnaz.org\\\/ministerio-cafe-en-colombia-empieza-a-consolidarse\\\/\",\"name\":\"MINISTERIO CAFE EN COLOMBIA EMPIEZA A CONSOLIDARSE | Iglesia del Nazareno Am\u00e9rica del Sur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/ministerio-cafe-en-colombia-empieza-a-consolidarse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/ministerio-cafe-en-colombia-empieza-a-consolidarse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samnaz.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Pantallazos-CAFE-Colombia.png\",\"datePublished\":\"2021-08-27T01:45:49+00:00\",\"dateModified\":\"2021-11-26T14:09:04+00:00\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.samnaz.org\\\/ministerio-cafe-en-colombia-empieza-a-consolidarse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/ministerio-cafe-en-colombia-empieza-a-consolidarse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.samnaz.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Pantallazos-CAFE-Colombia.png\",\"contentUrl\":\"https:\\\/\\\/www.samnaz.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Pantallazos-CAFE-Colombia.png\",\"width\":1920,\"height\":1080},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#website\",\"url\":\"https:\\\/\\\/www.samnaz.org\\\/\",\"name\":\"Haciendo Disc\u00edpulos Semejantes a Cristo en las naciones\",\"description\":\"Haciendo disc\u00edpulos semejantes a Cristo en las Naciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#organization\"},\"alternateName\":\"Viviendo la Gran Comisi\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.samnaz.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#organization\",\"name\":\"Iglesia del Nazareno Am\u00e9rica del Sur\",\"url\":\"https:\\\/\\\/www.samnaz.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.samnaz.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Logo-3-ESP.png\",\"contentUrl\":\"https:\\\/\\\/www.samnaz.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Logo-3-ESP.png\",\"width\":1041,\"height\":780,\"caption\":\"Iglesia del Nazareno Am\u00e9rica del Sur\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazarenoEsp\",\"https:\\\/\\\/www.instagram.com\\\/nazarenoesp\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/www.samnaz.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.samnaz.org\\\/#\\\/schema\\\/person\\\/c09d1131c49ba510c7e1cbb677b39927\",\"name\":\"Samnaz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5baaf0e270319d09c0efce6a9dd03ff93175913c70afe26595c0069c83fa6dc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5baaf0e270319d09c0efce6a9dd03ff93175913c70afe26595c0069c83fa6dc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5baaf0e270319d09c0efce6a9dd03ff93175913c70afe26595c0069c83fa6dc?s=96&d=mm&r=g\",\"caption\":\"Samnaz\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"MINISTERIO CAFE EN COLOMBIA EMPIEZA A CONSOLIDARSE | Iglesia del Nazareno Am\u00e9rica del Sur","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"MINISTERIO CAFE EN COLOMBIA EMPIEZA A CONSOLIDARSE | Iglesia del Nazareno Am\u00e9rica del Sur","og_url":"https:\/\/www.samnaz.org\/pt\/ministerio-cafe-en-colombia-empieza-a-consolidarse\/","og_site_name":"Iglesia del Nazareno Am\u00e9rica del Sur","article_publisher":"https:\/\/www.facebook.com\/NazarenoEsp","article_published_time":"2021-08-27T01:45:49+00:00","article_modified_time":"2021-11-26T14:09:04+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.samnaz.org\/wp-content\/uploads\/2021\/08\/Pantallazos-CAFE-Colombia.png","type":"image\/png"}],"author":"Samnaz","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Samnaz","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.samnaz.org\/ministerio-cafe-en-colombia-empieza-a-consolidarse\/#article","isPartOf":{"@id":"https:\/\/www.samnaz.org\/ministerio-cafe-en-colombia-empieza-a-consolidarse\/"},"author":{"name":"Samnaz","@id":"https:\/\/www.samnaz.org\/#\/schema\/person\/c09d1131c49ba510c7e1cbb677b39927"},"headline":"MINISTERIO CAFE EN COLOMBIA EMPIEZA A CONSOLIDARSE","datePublished":"2021-08-27T01:45:49+00:00","dateModified":"2021-11-26T14:09:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.samnaz.org\/ministerio-cafe-en-colombia-empieza-a-consolidarse\/"},"wordCount":319,"publisher":{"@id":"https:\/\/www.samnaz.org\/#organization"},"image":{"@id":"https:\/\/www.samnaz.org\/ministerio-cafe-en-colombia-empieza-a-consolidarse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.samnaz.org\/wp-content\/uploads\/2021\/08\/Pantallazos-CAFE-Colombia.png","articleSection":["Colombia","Matrimonios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.samnaz.org\/ministerio-cafe-en-colombia-empieza-a-consolidarse\/","url":"https:\/\/www.samnaz.org\/ministerio-cafe-en-colombia-empieza-a-consolidarse\/","name":"MINISTERIO CAFE EN COLOMBIA EMPIEZA A CONSOLIDARSE | Iglesia del Nazareno Am\u00e9rica del Sur","isPartOf":{"@id":"https:\/\/www.samnaz.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.samnaz.org\/ministerio-cafe-en-colombia-empieza-a-consolidarse\/#primaryimage"},"image":{"@id":"https:\/\/www.samnaz.org\/ministerio-cafe-en-colombia-empieza-a-consolidarse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.samnaz.org\/wp-content\/uploads\/2021\/08\/Pantallazos-CAFE-Colombia.png","datePublished":"2021-08-27T01:45:49+00:00","dateModified":"2021-11-26T14:09:04+00:00","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.samnaz.org\/ministerio-cafe-en-colombia-empieza-a-consolidarse\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.samnaz.org\/ministerio-cafe-en-colombia-empieza-a-consolidarse\/#primaryimage","url":"https:\/\/www.samnaz.org\/wp-content\/uploads\/2021\/08\/Pantallazos-CAFE-Colombia.png","contentUrl":"https:\/\/www.samnaz.org\/wp-content\/uploads\/2021\/08\/Pantallazos-CAFE-Colombia.png","width":1920,"height":1080},{"@type":"WebSite","@id":"https:\/\/www.samnaz.org\/#website","url":"https:\/\/www.samnaz.org\/","name":"Haciendo Disc\u00edpulos Semejantes a Cristo en las naciones","description":"Haciendo disc\u00edpulos semejantes a Cristo en las Naciones","publisher":{"@id":"https:\/\/www.samnaz.org\/#organization"},"alternateName":"Viviendo la Gran Comisi\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.samnaz.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.samnaz.org\/#organization","name":"Iglesia del Nazareno Am\u00e9rica del Sur","url":"https:\/\/www.samnaz.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.samnaz.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.samnaz.org\/wp-content\/uploads\/2021\/04\/Logo-3-ESP.png","contentUrl":"https:\/\/www.samnaz.org\/wp-content\/uploads\/2021\/04\/Logo-3-ESP.png","width":1041,"height":780,"caption":"Iglesia del Nazareno Am\u00e9rica del Sur"},"image":{"@id":"https:\/\/www.samnaz.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazarenoEsp","https:\/\/www.instagram.com\/nazarenoesp\/"],"publishingPrinciples":"https:\/\/www.samnaz.org\/"},{"@type":"Person","@id":"https:\/\/www.samnaz.org\/#\/schema\/person\/c09d1131c49ba510c7e1cbb677b39927","name":"Samnaz","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a5baaf0e270319d09c0efce6a9dd03ff93175913c70afe26595c0069c83fa6dc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a5baaf0e270319d09c0efce6a9dd03ff93175913c70afe26595c0069c83fa6dc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a5baaf0e270319d09c0efce6a9dd03ff93175913c70afe26595c0069c83fa6dc?s=96&d=mm&r=g","caption":"Samnaz"}}]}},"_links":{"self":[{"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/posts\/37033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/comments?post=37033"}],"version-history":[{"count":1,"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/posts\/37033\/revisions"}],"predecessor-version":[{"id":37063,"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/posts\/37033\/revisions\/37063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/media\/37034"}],"wp:attachment":[{"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/media?parent=37033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/categories?post=37033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.samnaz.org\/pt\/wp-json\/wp\/v2\/tags?post=37033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}